{"id":4689,"count":2,"description":"","link":"https:\/\/axunitedgroup.net\/Retail\/product-category\/%d9%87%d9%88%d9%86%d8%ac-%d9%83%d9%88%d9%86%d8%ac-2\/%d8%a3%d8%af%d9%88%d8%a7%d8%aa-%d9%83%d9%87%d8%b1%d8%a8%d9%8a%d8%a9-%d9%87%d9%88%d9%86%d8%ac-%d9%83%d9%88%d9%86%d8%ac-2\/%d9%83%d8%a7%d8%a8%d8%a7%d9%84%d8%a7%d8%aa-%d9%86%d8%aa-%d8%a3%d8%af%d9%88%d8%a7%d8%aa-%d9%83%d9%87%d8%b1%d8%a8%d9%8a%d8%a9-%d9%87%d9%88%d9%86%d8%ac-%d9%83%d9%88%d9%86%d8%ac-2\/","name":"\u0643\u0627\u0628\u0627\u0644\u0627\u062a \u0646\u062a","slug":"%d9%83%d8%a7%d8%a8%d8%a7%d9%84%d8%a7%d8%aa-%d9%86%d8%aa-%d8%a3%d8%af%d9%88%d8%a7%d8%aa-%d9%83%d9%87%d8%b1%d8%a8%d9%8a%d8%a9-%d9%87%d9%88%d9%86%d8%ac-%d9%83%d9%88%d9%86%d8%ac-2","taxonomy":"product_cat","parent":4590,"meta":[],"_links":{"self":[{"href":"https:\/\/axunitedgroup.net\/Retail\/wp-json\/wp\/v2\/product_cat\/4689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axunitedgroup.net\/Retail\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/axunitedgroup.net\/Retail\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/axunitedgroup.net\/Retail\/wp-json\/wp\/v2\/product_cat\/4590"}],"wp:post_type":[{"href":"https:\/\/axunitedgroup.net\/Retail\/wp-json\/wp\/v2\/product?product_cat=4689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}